{"id":2550,"date":"2016-04-12T13:25:27","date_gmt":"2016-04-12T12:25:27","guid":{"rendered":"http:\/\/dvworldtour.com\/?p=2550"},"modified":"2016-04-14T15:30:42","modified_gmt":"2016-04-14T14:30:42","slug":"le-japon-en-fleurs","status":"publish","type":"post","link":"https:\/\/dvworldtour.com\/index.php\/2016\/04\/12\/le-japon-en-fleurs\/","title":{"rendered":"Le Japon en fleurs !!!"},"content":{"rendered":"<p>Bonjour \u00e0 tous et toutes,<\/p>\n<p>Nous sommes actuellement \u00e0 Kyoto, o\u00f9 nous profitons pleinement de la ville et de la fin de la saison des sakuras. C&rsquo;est vraiment une merveille et nous ne regrettons pas d&rsquo;avoir choisi cette p\u00e9riode pour visiter le Japon.<\/p>\n<p>Un tr\u00e8s bon anniversaire \u00e0 tantine Christine ! \ud83d\ude42<\/p>\n<p>Gros bisous a tous et toutes<br \/>\nMerci \u00e0 vous tous qui nous suivez, chacun de vos messages nous fait chaud au coeur !<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour \u00e0 tous et toutes, Nous sommes actuellement \u00e0 Kyoto, o\u00f9 nous profitons pleinement de la ville et de la fin de la saison des sakuras. C&rsquo;est vraiment une merveille et nous ne regrettons pas d&rsquo;avoir choisi cette p\u00e9riode pour visiter le Japon. Un tr\u00e8s bon anniversaire \u00e0 tantine Christine ! \ud83d\ude42 Gros bisous a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":239,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":["post-2550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-japon"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/dvworldtour.com\/wp-content\/uploads\/2016\/01\/info-blog.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7bYsq-F8","_links":{"self":[{"href":"https:\/\/dvworldtour.com\/index.php\/wp-json\/wp\/v2\/posts\/2550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dvworldtour.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dvworldtour.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dvworldtour.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dvworldtour.com\/index.php\/wp-json\/wp\/v2\/comments?post=2550"}],"version-history":[{"count":1,"href":"https:\/\/dvworldtour.com\/index.php\/wp-json\/wp\/v2\/posts\/2550\/revisions"}],"predecessor-version":[{"id":2551,"href":"https:\/\/dvworldtour.com\/index.php\/wp-json\/wp\/v2\/posts\/2550\/revisions\/2551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dvworldtour.com\/index.php\/wp-json\/wp\/v2\/media\/239"}],"wp:attachment":[{"href":"https:\/\/dvworldtour.com\/index.php\/wp-json\/wp\/v2\/media?parent=2550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dvworldtour.com\/index.php\/wp-json\/wp\/v2\/categories?post=2550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dvworldtour.com\/index.php\/wp-json\/wp\/v2\/tags?post=2550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}